{"id":1020,"date":"2022-01-24T07:38:19","date_gmt":"2022-01-24T01:38:19","guid":{"rendered":"https:\/\/r2-toys.com\/?post_type=product&#038;p=1020"},"modified":"2023-10-05T20:39:22","modified_gmt":"2023-10-05T14:39:22","slug":"electrostaff-purge-trooper-jedi-fallen-order","status":"publish","type":"product","link":"https:\/\/r2-toys.com\/index.php\/product\/electrostaff-purge-trooper-jedi-fallen-order\/","title":{"rendered":"ELECTROSTAFF PURGE TROOPER GAMING GREATS"},"content":{"rendered":"<p>Los Purge Troopers son una clase especializada de soldados imperiales entrenados y equipados para ayudar a los inquisidores a cazar Jedi.<\/p>\n<p>La figura exclusiva de Electrostaff Purge Trooper de Gaming Greats \u00a0de 15 cm est\u00e1 detallada para parecerse al personaje del videojuego Star Wars Jedi: Fallen Order, con detalles premium y m\u00faltiples puntos de articulaci\u00f3n.<\/p>\n<p>\u26a0\ufe0f ADVERTENCIA: PELIGRO DE ASFIXIA &#8211; Piezas peque\u00f1as. No apto para ni\u00f1os menores de 4 a\u00f1os.<\/p>\n<p>Los productos Star Wars son producidos por Hasbro bajo licencia de Lucasfilm Ltd.<\/p>\n<p>Hasbro y todos los t\u00e9rminos relacionados son marcas registradas de Hasbro.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Los Purge Troopers son una clase especializada de soldados imperiales entrenados y equipados para ayudar a los inquisidores a cazar Jedi.<\/p>\n","protected":false},"featured_media":2466,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[28],"product_tag":[],"class_list":["post-1020","product","type-product","status-publish","has-post-thumbnail","product_cat-black-series","first","outofstock","taxable","shipping-taxable","purchasable","product-type-simple"],"_links":{"self":[{"href":"https:\/\/r2-toys.com\/index.php\/wp-json\/wp\/v2\/product\/1020","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/r2-toys.com\/index.php\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/r2-toys.com\/index.php\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/r2-toys.com\/index.php\/wp-json\/wp\/v2\/comments?post=1020"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/r2-toys.com\/index.php\/wp-json\/wp\/v2\/media\/2466"}],"wp:attachment":[{"href":"https:\/\/r2-toys.com\/index.php\/wp-json\/wp\/v2\/media?parent=1020"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/r2-toys.com\/index.php\/wp-json\/wp\/v2\/product_brand?post=1020"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/r2-toys.com\/index.php\/wp-json\/wp\/v2\/product_cat?post=1020"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/r2-toys.com\/index.php\/wp-json\/wp\/v2\/product_tag?post=1020"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}