{"id":4225,"date":"2022-04-22T01:00:01","date_gmt":"2022-04-21T19:00:01","guid":{"rendered":"https:\/\/r2-toys.com\/?post_type=product&#038;p=4225"},"modified":"2026-02-26T11:07:55","modified_gmt":"2026-02-26T05:07:55","slug":"arc-trooper-jesse","status":"publish","type":"product","link":"https:\/\/r2-toys.com\/index.php\/product\/arc-trooper-jesse\/","title":{"rendered":"ARC Trooper Jesse"},"content":{"rendered":"<p>Jesse es un patriota luchador que lleva con orgullo el s\u00edmbolo en forma de engranaje de la Rep\u00fablica Gal\u00e1ctica en su casco y tiene un gran tatuaje que cubre su rostro.<\/p>\n<p>Esta figura de 9,5 cm cuenta con un excelente<span class=\"Apple-converted-space\">\u00a0 <\/span>dise\u00f1o, en empaques inspirados en la l\u00ednea original e incluye 5 accesorios.<\/p>\n<p>Edad recomendada: 4 a\u00f1os en adelante<\/p>\n<p>\u26a0\ufe0fADVERTENCIA: PELIGRO DE ASFIXIA &#8211; Piezas peque\u00f1as. No apto para ni\u00f1os menores de 4 a\u00f1os.<\/p>\n<p>Los productos Star Wars son producidos por Hasbro bajo licencia de Lucasfilm Ltd.<\/p>\n<p>Hasbro y todos los t\u00e9rminos relacionados son marcas registradas de Hasbro.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Jesse es un patriota luchador que lleva con orgullo el s\u00edmbolo en forma de engranaje de la Rep\u00fablica Gal\u00e1ctica en su casco y tiene un gran tatuaje que cubre su rostro.<\/p>\n","protected":false},"featured_media":5118,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[29],"product_tag":[],"class_list":{"0":"post-4225","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-vintage","8":"first","9":"instock","10":"taxable","11":"shipping-taxable","12":"purchasable","13":"product-type-simple"},"_links":{"self":[{"href":"https:\/\/r2-toys.com\/index.php\/wp-json\/wp\/v2\/product\/4225","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/r2-toys.com\/index.php\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/r2-toys.com\/index.php\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/r2-toys.com\/index.php\/wp-json\/wp\/v2\/comments?post=4225"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/r2-toys.com\/index.php\/wp-json\/wp\/v2\/media\/5118"}],"wp:attachment":[{"href":"https:\/\/r2-toys.com\/index.php\/wp-json\/wp\/v2\/media?parent=4225"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/r2-toys.com\/index.php\/wp-json\/wp\/v2\/product_brand?post=4225"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/r2-toys.com\/index.php\/wp-json\/wp\/v2\/product_cat?post=4225"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/r2-toys.com\/index.php\/wp-json\/wp\/v2\/product_tag?post=4225"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}