{"id":4923,"date":"2023-01-16T07:53:46","date_gmt":"2023-01-16T01:53:46","guid":{"rendered":"https:\/\/r2-toys.com\/?post_type=product&#038;p=4923"},"modified":"2023-01-16T07:54:03","modified_gmt":"2023-01-16T01:54:03","slug":"ben-kenobi-retro-series-572-exclusive","status":"publish","type":"product","link":"https:\/\/r2-toys.com\/index.php\/product\/ben-kenobi-retro-series-572-exclusive\/","title":{"rendered":"Ben Kenobi Retro Series (572)  Exclusive"},"content":{"rendered":"<p>Un legendario Maestro Jedi, Obi-Wan Kenobi era un hombre noble y dotado en los caminos de la Fuerza. Entren\u00f3 a Anakin Skywalker, sirvi\u00f3 como general en el Ej\u00e9rcito de la Rep\u00fablica durante las Guerras Clon y gui\u00f3 a Luke Skywalker como mentor.<\/p>\n<p>Desde 1977 la saga de Star Wars ha sido un movimiento revolucionario de la cultura pop generaci\u00f3n tras generaci\u00f3n, reclutando fans y seguidores, creando para ellos diversas producciones del amplio universo. Gracias a FunkoPop podemos tener incre\u00edbles figuras de tus personajes favoritos con incre\u00edbles dise\u00f1os.<\/p>\n<p>Altura aproximada de 11 cm<\/p>\n<p>Empaque con ventana para su exhibici\u00f3n<\/p>\n<p>Fabricados en Vinyl<\/p>\n<p>Edad recomendada: 4 a\u00f1os en adelante<\/p>\n<p>\u26a0\ufe0fADVERTENCIA: PELIGRO DE ASFIXIA &#8211; Piezas peque\u00f1as. No apto para ni\u00f1os menores de 4 a\u00f1os.<\/p>\n<p>Los productos Star Wars son producidos por FUNKO bajo licencia de Lucasfilm Ltd. y Disney<\/p>\n<p>FUNKO, Target y todos los t\u00e9rminos relacionados son marcas registradas Funko y Target.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Un legendario Maestro Jedi, Obi-Wan Kenobi era un hombre noble y dotado en los caminos de la Fuerza. Entren\u00f3 a Anakin Skywalker, sirvi\u00f3 como general en el Ej\u00e9rcito de la Rep\u00fablica durante las Guerras Clon y gui\u00f3 a Luke Skywalker como mentor.<\/p>\n","protected":false},"featured_media":5531,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[20],"product_tag":[],"class_list":{"0":"post-4923","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-funko1","8":"first","9":"instock","10":"taxable","11":"shipping-taxable","12":"purchasable","13":"product-type-simple"},"_links":{"self":[{"href":"https:\/\/r2-toys.com\/index.php\/wp-json\/wp\/v2\/product\/4923","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/r2-toys.com\/index.php\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/r2-toys.com\/index.php\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/r2-toys.com\/index.php\/wp-json\/wp\/v2\/comments?post=4923"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/r2-toys.com\/index.php\/wp-json\/wp\/v2\/media\/5531"}],"wp:attachment":[{"href":"https:\/\/r2-toys.com\/index.php\/wp-json\/wp\/v2\/media?parent=4923"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/r2-toys.com\/index.php\/wp-json\/wp\/v2\/product_brand?post=4923"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/r2-toys.com\/index.php\/wp-json\/wp\/v2\/product_cat?post=4923"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/r2-toys.com\/index.php\/wp-json\/wp\/v2\/product_tag?post=4923"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}