{"id":6860,"date":"2024-02-21T04:40:33","date_gmt":"2024-02-20T22:40:33","guid":{"rendered":"https:\/\/r2-toys.com\/?post_type=product&#038;p=6860"},"modified":"2026-01-01T01:25:03","modified_gmt":"2025-12-31T19:25:03","slug":"luke-skywalker-grogu-2","status":"publish","type":"product","link":"https:\/\/r2-toys.com\/index.php\/product\/luke-skywalker-grogu-2\/","title":{"rendered":"Luke Skywalker &#038; Grogu"},"content":{"rendered":"<p>Luke Skywalker accedi\u00f3 a tomar al ni\u00f1o en su cuidado y entrenarlo en los caminos de la Fuerza. Despu\u00e9s de ser entregado por Djarin al ser rescatado de Gideon.<\/p>\n<p>Esta figura de 9,5 cm cuenta con un excelente<span class=\"Apple-converted-space\">\u00a0 <\/span>dise\u00f1o, en empaques inspirados en la l\u00ednea original e incluye 2 accesorio.<\/p>\n<p>Edad recomendada: 4 a\u00f1os en adelante<\/p>\n<p>\u26a0\ufe0fADVERTENCIA: PELIGRO DE ASFIXIA &#8211; Piezas peque\u00f1as. No apto para ni\u00f1os menores de 4 a\u00f1os.<\/p>\n<p>Los productos Star Wars son producidos por Hasbro bajo licencia de Lucasfilm Ltd.<\/p>\n<p>Hasbro y todos los t\u00e9rminos relacionados son marcas registradas de Hasbro.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Luke Skywalker accedi\u00f3 a tomar al ni\u00f1o en su cuidado y entrenarlo en los caminos de la Fuerza. Despu\u00e9s de ser entregado por Djarin al ser rescatado de Gideon.<\/p>\n","protected":false},"featured_media":6745,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[29],"product_tag":[],"class_list":{"0":"post-6860","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-vintage","8":"first","9":"instock","10":"taxable","11":"shipping-taxable","12":"purchasable","13":"product-type-simple"},"_links":{"self":[{"href":"https:\/\/r2-toys.com\/index.php\/wp-json\/wp\/v2\/product\/6860","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/r2-toys.com\/index.php\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/r2-toys.com\/index.php\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/r2-toys.com\/index.php\/wp-json\/wp\/v2\/comments?post=6860"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/r2-toys.com\/index.php\/wp-json\/wp\/v2\/media\/6745"}],"wp:attachment":[{"href":"https:\/\/r2-toys.com\/index.php\/wp-json\/wp\/v2\/media?parent=6860"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/r2-toys.com\/index.php\/wp-json\/wp\/v2\/product_brand?post=6860"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/r2-toys.com\/index.php\/wp-json\/wp\/v2\/product_cat?post=6860"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/r2-toys.com\/index.php\/wp-json\/wp\/v2\/product_tag?post=6860"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}