{"id":6869,"date":"2024-02-21T05:26:31","date_gmt":"2024-02-20T23:26:31","guid":{"rendered":"https:\/\/r2-toys.com\/?post_type=product&#038;p=6869"},"modified":"2026-03-29T05:15:57","modified_gmt":"2026-03-28T23:15:57","slug":"obi-wan-kenobi-shodown-darth-vader-duels-end","status":"publish","type":"product","link":"https:\/\/r2-toys.com\/index.php\/product\/obi-wan-kenobi-shodown-darth-vader-duels-end\/","title":{"rendered":"Obi Wan Kenobi (Showdown)- Darth Vader (Duel\u00b4s End)"},"content":{"rendered":"<p>Obi-Wan Kenobi se desarrolla a\u00f1os despu\u00e9s de los dram\u00e1ticos eventos de Star Wars: La venganza de los Sith, donde Kenobi enfrent\u00f3 la corrupci\u00f3n de su amigo y aprendiz de Jedi, Anakin Skywalker convertido en Lord Sith Darth Vader.<\/p>\n<p>Estas figuras de 9,5 cm cuenta con un excelente<span class=\"Apple-converted-space\">\u00a0 <\/span>dise\u00f1o, en empaques inspirados en la l\u00ednea original e incluye accesorios.<\/p>\n<p>Edad recomendada: 4 a\u00f1os en adelante<\/p>\n<p>\u26a0\ufe0fADVERTENCIA: PELIGRO DE ASFIXIA &#8211; Piezas peque\u00f1as. No apto para ni\u00f1os menores de 4 a\u00f1os.<\/p>\n<p>Los productos Star Wars son producidos por Hasbro bajo licencia de Lucasfilm Ltd.<\/p>\n<p>Hasbro y todos los t\u00e9rminos relacionados son marcas registradas de Hasbro.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Obi-Wan Kenobi se desarrolla a\u00f1os despu\u00e9s de los dram\u00e1ticos eventos de Star Wars: La venganza de los Sith, donde Kenobi enfrent\u00f3 la corrupci\u00f3n de su amigo y aprendiz de Jedi, Anakin Skywalker convertido en Lord Sith Darth Vader.<\/p>\n","protected":false},"featured_media":6778,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[29],"product_tag":[],"class_list":{"0":"post-6869","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-vintage","8":"first","9":"outofstock","10":"taxable","11":"shipping-taxable","12":"purchasable","13":"product-type-simple"},"_links":{"self":[{"href":"https:\/\/r2-toys.com\/index.php\/wp-json\/wp\/v2\/product\/6869","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/r2-toys.com\/index.php\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/r2-toys.com\/index.php\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/r2-toys.com\/index.php\/wp-json\/wp\/v2\/comments?post=6869"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/r2-toys.com\/index.php\/wp-json\/wp\/v2\/media\/6778"}],"wp:attachment":[{"href":"https:\/\/r2-toys.com\/index.php\/wp-json\/wp\/v2\/media?parent=6869"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/r2-toys.com\/index.php\/wp-json\/wp\/v2\/product_brand?post=6869"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/r2-toys.com\/index.php\/wp-json\/wp\/v2\/product_cat?post=6869"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/r2-toys.com\/index.php\/wp-json\/wp\/v2\/product_tag?post=6869"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}