{"id":7078,"date":"2024-03-19T11:24:52","date_gmt":"2024-03-19T05:24:52","guid":{"rendered":"https:\/\/r2-toys.com\/?post_type=product&#038;p=7078"},"modified":"2024-12-10T02:53:18","modified_gmt":"2024-12-09T20:53:18","slug":"jedi-knight-revan-hk-47","status":"publish","type":"product","link":"https:\/\/r2-toys.com\/index.php\/product\/jedi-knight-revan-hk-47\/","title":{"rendered":"Jedi Knight Revan &#038; HK-47"},"content":{"rendered":"<p>Fue un antiguo Lord Sith, quien era el hom\u00f3nimo de la \u00abLegi\u00f3n Revan\u00bb, la 3.\u00aa Legi\u00f3n de los soldados Sith del Sith Eterno de Darth Sidious. Debido a que la historia de los sith estaba escondida del resto de la galaxia, solo los cultistas del Sith Eterno conoc\u00edan el significado del nombre.<\/p>\n<p>Edad recomendada: 4 a\u00f1os en adelante<br \/>\n\u26a0\ufe0fADVERTENCIA: PELIGRO DE ASFIXIA &#8211; Piezas peque\u00f1as. No apto para ni\u00f1os menores de 4 a\u00f1os.<br \/>\nLos productos Star Wars son producidos por Hasbro bajo licencia de Lucasfilm Ltd.<br \/>\nHasbro y todos los t\u00e9rminos relacionados son marcas registradas de Hasbro.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Fue un antiguo Lord Sith, quien era el hom\u00f3nimo de la \u00abLegi\u00f3n Revan\u00bb, la 3.\u00aa Legi\u00f3n de los soldados Sith del Sith Eterno de Darth Sidious. Debido a que la historia de los sith estaba escondida del resto de la galaxia, solo los cultistas del Sith Eterno conoc\u00edan el significado del nombre.<\/p>\n","protected":false},"featured_media":7061,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[29],"product_tag":[],"class_list":["post-7078","product","type-product","status-publish","has-post-thumbnail","product_cat-vintage","first","outofstock","taxable","shipping-taxable","purchasable","product-type-simple"],"_links":{"self":[{"href":"https:\/\/r2-toys.com\/index.php\/wp-json\/wp\/v2\/product\/7078","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/r2-toys.com\/index.php\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/r2-toys.com\/index.php\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/r2-toys.com\/index.php\/wp-json\/wp\/v2\/comments?post=7078"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/r2-toys.com\/index.php\/wp-json\/wp\/v2\/media\/7061"}],"wp:attachment":[{"href":"https:\/\/r2-toys.com\/index.php\/wp-json\/wp\/v2\/media?parent=7078"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/r2-toys.com\/index.php\/wp-json\/wp\/v2\/product_brand?post=7078"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/r2-toys.com\/index.php\/wp-json\/wp\/v2\/product_cat?post=7078"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/r2-toys.com\/index.php\/wp-json\/wp\/v2\/product_tag?post=7078"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}