{"id":7439,"date":"2024-08-13T11:48:20","date_gmt":"2024-08-13T05:48:20","guid":{"rendered":"https:\/\/r2-toys.com\/?post_type=product&#038;p=7439"},"modified":"2024-08-13T11:48:20","modified_gmt":"2024-08-13T05:48:20","slug":"tha-uncanny-x-men-x-force-deadpool","status":"publish","type":"product","link":"https:\/\/r2-toys.com\/index.php\/product\/tha-uncanny-x-men-x-force-deadpool\/","title":{"rendered":"Tha Uncanny X-Men, X-Force Deadpool"},"content":{"rendered":"<p class=\"p1\">Edad recomendada: 4 a\u00f1os en adelante<\/p>\n<p class=\"p1\"><span class=\"s1\">\u26a0\ufe0f<\/span>ADVERTENCIA: PELIGRO DE ASFIXIA &#8211; Piezas peque\u00f1as. No apto para ni\u00f1os menores de 4 a\u00f1os.<\/p>\n<p class=\"p1\">Los productos Marvel son producidos por Hasbro bajo licencia de Marvel y Disney.<\/p>\n<p class=\"p1\">Marvel, Hasbro y Disney as\u00ed todos los t\u00e9rminos relacionados son marcas registradas.<\/p>\n","protected":false},"excerpt":{"rendered":"<p class=\"p1\">Edad recomendada: 4 a\u00f1os en adelante<\/p>\n<p class=\"p1\"><span class=\"s1\">\u26a0\ufe0f<\/span>ADVERTENCIA: PELIGRO DE ASFIXIA &#8211; Piezas peque\u00f1as. No apto para ni\u00f1os menores de 4 a\u00f1os.<\/p>\n<p class=\"p1\">Los productos Marvel son producidos por Hasbro bajo licencia de Marvel y Disney.<\/p>\n<p class=\"p1\">Marvel, Hasbro y Disney as\u00ed todos los t\u00e9rminos relacionados son marcas registradas.<\/p>\n","protected":false},"featured_media":7408,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[21],"product_tag":[],"class_list":{"0":"post-7439","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-retro","8":"first","9":"instock","10":"taxable","11":"shipping-taxable","12":"purchasable","13":"product-type-simple"},"_links":{"self":[{"href":"https:\/\/r2-toys.com\/index.php\/wp-json\/wp\/v2\/product\/7439","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/r2-toys.com\/index.php\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/r2-toys.com\/index.php\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/r2-toys.com\/index.php\/wp-json\/wp\/v2\/comments?post=7439"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/r2-toys.com\/index.php\/wp-json\/wp\/v2\/media\/7408"}],"wp:attachment":[{"href":"https:\/\/r2-toys.com\/index.php\/wp-json\/wp\/v2\/media?parent=7439"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/r2-toys.com\/index.php\/wp-json\/wp\/v2\/product_brand?post=7439"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/r2-toys.com\/index.php\/wp-json\/wp\/v2\/product_cat?post=7439"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/r2-toys.com\/index.php\/wp-json\/wp\/v2\/product_tag?post=7439"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}