{"id":7441,"date":"2024-08-13T11:53:10","date_gmt":"2024-08-13T05:53:10","guid":{"rendered":"https:\/\/r2-toys.com\/?post_type=product&#038;p=7441"},"modified":"2025-12-06T12:41:14","modified_gmt":"2025-12-06T06:41:14","slug":"scarlet-spider","status":"publish","type":"product","link":"https:\/\/r2-toys.com\/index.php\/product\/scarlet-spider\/","title":{"rendered":"Scarlet Spider"},"content":{"rendered":"<p class=\"p1\">Edad recomendada: 4 a\u00f1os en adelante<\/p>\n<p class=\"p1\"><span class=\"s1\">\u26a0\ufe0f<\/span>ADVERTENCIA: PELIGRO DE ASFIXIA &#8211; Piezas peque\u00f1as. No apto para ni\u00f1os menores de 4 a\u00f1os.<\/p>\n<p class=\"p1\">Los productos Marvel son producidos por Hasbro bajo licencia de Marvel y Disney.<\/p>\n<p class=\"p1\">Marvel, Hasbro y Disney as\u00ed todos los t\u00e9rminos relacionados son marcas registradas.<\/p>\n","protected":false},"excerpt":{"rendered":"<p class=\"p1\">Edad recomendada: 4 a\u00f1os en adelante<\/p>\n<p class=\"p1\"><span class=\"s1\">\u26a0\ufe0f<\/span>ADVERTENCIA: PELIGRO DE ASFIXIA &#8211; Piezas peque\u00f1as. No apto para ni\u00f1os menores de 4 a\u00f1os.<\/p>\n<p class=\"p1\">Los productos Marvel son producidos por Hasbro bajo licencia de Marvel y Disney.<\/p>\n<p class=\"p1\">Marvel, Hasbro y Disney as\u00ed todos los t\u00e9rminos relacionados son marcas registradas.<\/p>\n","protected":false},"featured_media":7412,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[21],"product_tag":[],"class_list":{"0":"post-7441","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-retro","8":"first","9":"outofstock","10":"taxable","11":"shipping-taxable","12":"purchasable","13":"product-type-simple"},"_links":{"self":[{"href":"https:\/\/r2-toys.com\/index.php\/wp-json\/wp\/v2\/product\/7441","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/r2-toys.com\/index.php\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/r2-toys.com\/index.php\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/r2-toys.com\/index.php\/wp-json\/wp\/v2\/comments?post=7441"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/r2-toys.com\/index.php\/wp-json\/wp\/v2\/media\/7412"}],"wp:attachment":[{"href":"https:\/\/r2-toys.com\/index.php\/wp-json\/wp\/v2\/media?parent=7441"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/r2-toys.com\/index.php\/wp-json\/wp\/v2\/product_brand?post=7441"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/r2-toys.com\/index.php\/wp-json\/wp\/v2\/product_cat?post=7441"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/r2-toys.com\/index.php\/wp-json\/wp\/v2\/product_tag?post=7441"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}