{"id":7483,"date":"2024-08-22T10:20:00","date_gmt":"2024-08-22T04:20:00","guid":{"rendered":"https:\/\/r2-toys.com\/?post_type=product&#038;p=7483"},"modified":"2024-08-22T10:20:37","modified_gmt":"2024-08-22T04:20:37","slug":"7483","status":"publish","type":"product","link":"https:\/\/r2-toys.com\/index.php\/product\/7483\/","title":{"rendered":"Rebel Trooper &#038; Stormtrooper"},"content":{"rendered":"<p class=\"p1\">Esta figura de 15 cm cuenta con un excelente<span class=\"Apple-converted-space\">\u00a0 <\/span>dise\u00f1o.<\/p>\n<p class=\"p1\">Edad recomendada: 4 a\u00f1os en adelante<\/p>\n<p class=\"p1\"><span class=\"s1\">\u26a0\ufe0f<\/span>ADVERTENCIA: PELIGRO DE ASFIXIA &#8211; Piezas peque\u00f1as. No apto para ni\u00f1os menores de 4 a\u00f1os.<\/p>\n<p class=\"p1\">Los productos Star Wars son producidos por Hasbro bajo licencia de Lucasfilm Ltd.<\/p>\n<p class=\"p1\">Hasbro y todos los t\u00e9rminos relacionados son marcas registradas de Hasbro.<\/p>\n","protected":false},"excerpt":{"rendered":"<p class=\"p1\">Esta figura de 15 cm cuenta con un excelente<span class=\"Apple-converted-space\">\u00a0 <\/span>dise\u00f1o.<\/p>\n<p class=\"p1\">Edad recomendada: 4 a\u00f1os en adelante<\/p>\n<p class=\"p1\"><span class=\"s1\">\u26a0\ufe0f<\/span>ADVERTENCIA: PELIGRO DE ASFIXIA &#8211; Piezas peque\u00f1as. No apto para ni\u00f1os menores de 4 a\u00f1os.<\/p>\n<p class=\"p1\">Los productos Star Wars son producidos por Hasbro bajo licencia de Lucasfilm Ltd.<\/p>\n<p class=\"p1\">Hasbro y todos los t\u00e9rminos relacionados son marcas registradas de Hasbro.<\/p>\n","protected":false},"featured_media":7472,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[28],"product_tag":[],"class_list":{"0":"post-7483","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-black-series","8":"first","9":"instock","10":"taxable","11":"shipping-taxable","12":"purchasable","13":"product-type-simple"},"_links":{"self":[{"href":"https:\/\/r2-toys.com\/index.php\/wp-json\/wp\/v2\/product\/7483","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/r2-toys.com\/index.php\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/r2-toys.com\/index.php\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/r2-toys.com\/index.php\/wp-json\/wp\/v2\/comments?post=7483"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/r2-toys.com\/index.php\/wp-json\/wp\/v2\/media\/7472"}],"wp:attachment":[{"href":"https:\/\/r2-toys.com\/index.php\/wp-json\/wp\/v2\/media?parent=7483"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/r2-toys.com\/index.php\/wp-json\/wp\/v2\/product_brand?post=7483"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/r2-toys.com\/index.php\/wp-json\/wp\/v2\/product_cat?post=7483"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/r2-toys.com\/index.php\/wp-json\/wp\/v2\/product_tag?post=7483"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}