{"id":8056,"date":"2025-08-13T01:28:54","date_gmt":"2025-08-12T19:28:54","guid":{"rendered":"https:\/\/r2-toys.com\/?post_type=product&#038;p=8056"},"modified":"2026-04-03T01:14:58","modified_gmt":"2026-04-02T19:14:58","slug":"cal-kestis-turgle-skoova-stev","status":"publish","type":"product","link":"https:\/\/r2-toys.com\/index.php\/product\/cal-kestis-turgle-skoova-stev\/","title":{"rendered":"CAL KESTIS TURGLE &#038; SKOOVA STEV"},"content":{"rendered":"<p class=\"p1\">Esta figura de 15 cm cuenta con un excelente<span class=\"Apple-converted-space\">\u00a0 <\/span>dise\u00f1o.<\/p>\n<p class=\"p1\">Edad recomendada: 4 a\u00f1os en adelante<\/p>\n<p class=\"p1\"><span class=\"s1\">\u26a0\ufe0f<\/span>ADVERTENCIA: PELIGRO DE ASFIXIA &#8211; Piezas peque\u00f1as. No apto para ni\u00f1os menores de 4 a\u00f1os.<\/p>\n<p class=\"p1\">Los productos Star Wars son producidos por Hasbro bajo licencia de Lucasfilm Ltd.<\/p>\n<p class=\"p1\">Hasbro y todos los t\u00e9rminos relacionados son marcas registradas de Hasbro.<\/p>\n","protected":false},"excerpt":{"rendered":"<p class=\"p1\">Esta figura de 15 cm cuenta con un excelente<span class=\"Apple-converted-space\">\u00a0 <\/span>dise\u00f1o.<\/p>\n<p class=\"p1\">Edad recomendada: 4 a\u00f1os en adelante<\/p>\n<p class=\"p1\"><span class=\"s1\">\u26a0\ufe0f<\/span>ADVERTENCIA: PELIGRO DE ASFIXIA &#8211; Piezas peque\u00f1as. No apto para ni\u00f1os menores de 4 a\u00f1os.<\/p>\n<p class=\"p1\">Los productos Star Wars son producidos por Hasbro bajo licencia de Lucasfilm Ltd.<\/p>\n<blockquote>\n<p class=\"p1\">Hasbro y todos los t\u00e9rminos relacionados son marcas registradas de Hasbro.9<\/p>\n<\/blockquote>\n","protected":false},"featured_media":8042,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[28],"product_tag":[],"class_list":["post-8056","product","type-product","status-publish","has-post-thumbnail","product_cat-black-series","first","instock","taxable","shipping-taxable","purchasable","product-type-simple"],"_links":{"self":[{"href":"https:\/\/r2-toys.com\/index.php\/wp-json\/wp\/v2\/product\/8056","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/r2-toys.com\/index.php\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/r2-toys.com\/index.php\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/r2-toys.com\/index.php\/wp-json\/wp\/v2\/comments?post=8056"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/r2-toys.com\/index.php\/wp-json\/wp\/v2\/media\/8042"}],"wp:attachment":[{"href":"https:\/\/r2-toys.com\/index.php\/wp-json\/wp\/v2\/media?parent=8056"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/r2-toys.com\/index.php\/wp-json\/wp\/v2\/product_brand?post=8056"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/r2-toys.com\/index.php\/wp-json\/wp\/v2\/product_cat?post=8056"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/r2-toys.com\/index.php\/wp-json\/wp\/v2\/product_tag?post=8056"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}