{"id":8333,"date":"2026-02-07T13:00:52","date_gmt":"2026-02-07T07:00:52","guid":{"rendered":"https:\/\/r2-toys.com\/?post_type=product&#038;p=8333"},"modified":"2026-02-07T13:00:52","modified_gmt":"2026-02-07T07:00:52","slug":"princess-leia-collector-doll","status":"publish","type":"product","link":"https:\/\/r2-toys.com\/index.php\/product\/princess-leia-collector-doll\/","title":{"rendered":"PRINCESS LEIA COLLECTOR DOLL"},"content":{"rendered":"<p class=\"p1\">Esta figura\u00a0 cuenta con un excelente<span class=\"Apple-converted-space\">\u00a0 <\/span>dise\u00f1o.<\/p>\n<p class=\"p1\">Edad recomendada: 12 a\u00f1os en adelante<\/p>\n<p class=\"p1\"><span class=\"s1\">\u26a0\ufe0f<\/span>ADVERTENCIA: PELIGRO DE ASFIXIA &#8211; Piezas peque\u00f1as. No apto para ni\u00f1os menores de 4 a\u00f1os.<\/p>\n<p class=\"p1\">Los productos Star Wars son producidos por Hasbro bajo licencia de Lucasfilm Ltd.<\/p>\n<p class=\"p1\">Hasbro y todos los t\u00e9rminos relacionados son marcas registradas de Hasbro.<\/p>\n","protected":false},"excerpt":{"rendered":"<p class=\"p1\">Esta figura\u00a0 cuenta con un excelente<span class=\"Apple-converted-space\">\u00a0 <\/span>dise\u00f1o.<\/p>\n<p class=\"p1\">Edad recomendada: 12 a\u00f1os en adelante<\/p>\n<p class=\"p1\"><span class=\"s1\">\u26a0\ufe0f<\/span>ADVERTENCIA: PELIGRO DE ASFIXIA &#8211; Piezas peque\u00f1as. No apto para ni\u00f1os menores de 4 a\u00f1os.<\/p>\n<p class=\"p1\">Los productos Star Wars son producidos por Hasbro bajo licencia de Lucasfilm Ltd.<\/p>\n<p class=\"p1\">Hasbro y todos los t\u00e9rminos relacionados son marcas registradas de Hasbro.<\/p>\n","protected":false},"featured_media":8281,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[33],"product_tag":[],"class_list":{"0":"post-8333","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-otros","8":"first","9":"instock","10":"taxable","11":"shipping-taxable","12":"purchasable","13":"product-type-simple"},"_links":{"self":[{"href":"https:\/\/r2-toys.com\/index.php\/wp-json\/wp\/v2\/product\/8333","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/r2-toys.com\/index.php\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/r2-toys.com\/index.php\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/r2-toys.com\/index.php\/wp-json\/wp\/v2\/comments?post=8333"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/r2-toys.com\/index.php\/wp-json\/wp\/v2\/media\/8281"}],"wp:attachment":[{"href":"https:\/\/r2-toys.com\/index.php\/wp-json\/wp\/v2\/media?parent=8333"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/r2-toys.com\/index.php\/wp-json\/wp\/v2\/product_brand?post=8333"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/r2-toys.com\/index.php\/wp-json\/wp\/v2\/product_cat?post=8333"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/r2-toys.com\/index.php\/wp-json\/wp\/v2\/product_tag?post=8333"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}